{"id":1183,"date":"2017-01-20T22:59:14","date_gmt":"2017-01-20T21:59:14","guid":{"rendered":"http:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/?p=1183"},"modified":"2017-01-21T23:03:24","modified_gmt":"2017-01-21T22:03:24","slug":"mobilita-concluso-il-confronto-sullarticolato","status":"publish","type":"post","link":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/","title":{"rendered":"Mobilit\u00e0: Concluso il confronto sull&#8217;articolato"},"content":{"rendered":"<h2 class=\"pane-title\">Concluso il confronto sull&#8217;articolato<\/h2>\n<p style=\"text-align: justify;\"><span class=\"temaNotiziaSinistra\">Mobilit\u00e0 <\/span><\/p>\n<p><span class=\"sottotitoloNotiziaSinistra\"> La prossima settimana possibile la sigla del contratto <\/span><\/p>\n<div class=\"testoNotiziaInterna\">\n<p style=\"text-align: justify;\">Il giorno 20 gennaio 2017 \u00e8 proseguito e si \u00e8 concluso l&#8217;esame dell&#8217;articolato relativo al contratto nazionale sulla mobilit\u00e0 del personale docente ed educativo. Per il personale Ata ci sono ancora aspetti da definire. La prossima settimana, dopo una rilettura e una messa a punto del testo ci potrebbe essere la sigla del contratto.<\/p>\n<p style=\"text-align: justify;\">L&#8217;articolato recepisce pienamente quanto stabilito dall&#8217;accordo politico sottoscritto tra le parti il 29 dicembre. Di seguito riportiamo le modifiche pi\u00f9 significative.<\/p>\n<p style=\"text-align: justify;\"><strong>Personale docente <\/strong><br \/>\nDetto personale con un&#8217;unica domanda potr\u00e0 esprimere fino ad un massimo di 15 opzioni, sia provinciali che interprovinciali. La mobilit\u00e0 potr\u00e0 essere effettuata da scuola a scuola, da ambito a scuola e viceversa. Nel limite delle 15 opzioni possono essere richieste anche pi\u00f9 province, l&#8217;unico limite \u00e8 relativo alla scelta delle scuole che non possono essere pi\u00f9 di 5. Nel caso di mobilit\u00e0 su scuola si acquisir\u00e0 la titolarit\u00e0 di scuola, nel caso di scelta di ambito o di codice sintetico di provincia si acquisir\u00e0 la titolarit\u00e0 di ambito. Una delle novit\u00e0 proposte dall&#8217;amministrazione riguarda le scuole secondarie di I e II grado con sezioni che ricadono in comuni diversi che avranno un organico unico. Nel caso specifico le parti hanno convenuto che i criteri e le modalit\u00e0 dell&#8217;assegnazione dei docenti alle varie sedi venga definito dalla contrattazione d&#8217;istituto.<\/p>\n<p style=\"text-align: justify;\"><strong>Licei musicali<\/strong><br \/>\nPer la mobilit\u00e0 professionale verso i posti delle nuove classi di concorso sono riservati il 50% di tutti i posti interi vacanti e disponibili. In caso di resto dispari il posto residuo viene comunque assegnato alla mobilit\u00e0 professionale.<\/p>\n<p style=\"text-align: justify;\"><strong>Sistema delle precedenze <\/strong><br \/>\nLe parti, per dare un segnale di attenzione ai familiari che assistono persone con disabilit\u00e0, hanno deciso di dare priorit\u00e0 all&#8217;assistenza al figlio, al coniuge e al genitore disabile rispetto alla precedenza per il rientro nel comune di precedente titolarit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Individuazione e trattamento perdenti posto<\/strong><br \/>\nAi fini del l&#8217;individuazione del docente soprannumerario, per ogni ordine di scuola e tipologia di posto, si formuler\u00e0 una graduatoria unica, senza distinzione tra titolari di scuola e di ambito. I criteri di individuazione del perdente posto restano invariati e i docenti ultimi arrivati per mobilit\u00e0 a domanda, indipendentemente dal punteggio, saranno collocati in fondo alla graduatoria e saranno i primi ad essere individuati nel caso di contrazione dell&#8217;organico. Sia per il rientro nella scuola che nel comune di precedente titolarit\u00e0 rimane invariato il diritto alla precedenza per il personale trasferito d&#8217;ufficio negli ultimi otto anni.<\/p>\n<p style=\"text-align: justify;\"><strong>Personale educativo <\/strong><br \/>\nAumentate da tre a nove le province esprimibili. Si potranno esprimere preferenze per non pi\u00f9 di nove province oltre a quella di titolarit\u00e0. Per questo personale c&#8217;\u00e8 l&#8217;impegno dell&#8217;amministrazione, su richiesta UIL, ad adottare per il prossimo anno la procedura On-line per la presentazione delle domande.<\/p>\n<p style=\"text-align: justify;\"><strong>Tabelle di valutazione <\/strong><br \/>\nLe parti hanno deciso di equiparare, ai soli fini della mobilit\u00e0 a domanda, il servizio di pre ruolo e altro ruolo a quello di ruolo.<\/p>\n<p style=\"text-align: justify;\"><strong>Personale Ata <\/strong><br \/>\nLe questioni relative al personale Ata verranno definite nel corso del prossimo incontro gi\u00e0 programmato per marted\u00ec 24 gennaio. Dopo la sigla il testo dovr\u00e0 essere inviato al MEF e alla funzione Pubblica per i pareri di competenza. Solo successivamente si proceder\u00e0 all&#8217;eventuale firma definitiva del contratto.<\/p>\n<p style=\"text-align: justify;\">Ai fini dall&#8217;esito positivo del contratto sulla mobilit\u00e0, per la UIL resta prioritaria la definizione dell&#8217;accordo, mediante l&#8217;individuazione di procedure imparziali e trasparenti, per il passaggio del personale docente da ambito a scuola.<br \/>\nI due aspetti sono fortemente collegati e i due percorsi dovranno concludersi contemporaneamente.<\/p>\n<\/div>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=UILScuolaBO_ER\" class=\"twitter-share-button\" data-size=\"large\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Concluso il confronto sull&#8217;articolato Mobilit\u00e0 La prossima settimana possibile la sigla del contratto Il giorno 20 gennaio 2017 \u00e8 proseguito e si \u00e8 concluso l&#8217;esame &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,5,12,6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Mobilit\u00e0: Concluso il confronto sull&#039;articolato - Uil Scuola Emilia Romagna<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Mobilit\u00e0: Concluso il confronto sull&#039;articolato - Uil Scuola Emilia Romagna\" \/>\r\n<meta property=\"og:description\" content=\"Concluso il confronto sull&#8217;articolato Mobilit\u00e0 La prossima settimana possibile la sigla del contratto Il giorno 20 gennaio 2017 \u00e8 proseguito e si \u00e8 concluso l&#8217;esame &hellip;\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Uil Scuola Emilia Romagna\" \/>\r\n<meta property=\"article:published_time\" content=\"2017-01-20T21:59:14+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2017-01-21T22:03:24+00:00\" \/>\r\n<meta name=\"author\" content=\"admin\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/person\/f42878fd07a4b6ba2b7153d4fad5de5e\"},\"headline\":\"Mobilit\u00e0: Concluso il confronto sull&#8217;articolato\",\"datePublished\":\"2017-01-20T21:59:14+00:00\",\"dateModified\":\"2017-01-21T22:03:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/\"},\"wordCount\":578,\"publisher\":{\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#organization\"},\"articleSection\":[\"ATA\",\"Mobilit\u00e0\",\"Notizie\",\"Personale Docente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/\",\"url\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/\",\"name\":\"Mobilit\u00e0: Concluso il confronto sull'articolato - Uil Scuola Emilia Romagna\",\"isPartOf\":{\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#website\"},\"datePublished\":\"2017-01-20T21:59:14+00:00\",\"dateModified\":\"2017-01-21T22:03:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mobilit\u00e0: Concluso il confronto sull&#8217;articolato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#website\",\"url\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/\",\"name\":\"Uil Scuola Emilia Romagna\",\"description\":\"La voce libera della scuola\",\"publisher\":{\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#organization\",\"name\":\"Uil Scuola Emilia Romagna\",\"url\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-content\/uploads\/2017\/04\/cropped-header.png\",\"contentUrl\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-content\/uploads\/2017\/04\/cropped-header.png\",\"width\":1000,\"height\":150,\"caption\":\"Uil Scuola Emilia Romagna\"},\"image\":{\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/person\/f42878fd07a4b6ba2b7153d4fad5de5e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aebf815ae2f30ffdae8b8c247273d34c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aebf815ae2f30ffdae8b8c247273d34c?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/author\/admin\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mobilit\u00e0: Concluso il confronto sull'articolato - Uil Scuola Emilia Romagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/","og_locale":"it_IT","og_type":"article","og_title":"Mobilit\u00e0: Concluso il confronto sull'articolato - Uil Scuola Emilia Romagna","og_description":"Concluso il confronto sull&#8217;articolato Mobilit\u00e0 La prossima settimana possibile la sigla del contratto Il giorno 20 gennaio 2017 \u00e8 proseguito e si \u00e8 concluso l&#8217;esame &hellip;","og_url":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/","og_site_name":"Uil Scuola Emilia Romagna","article_published_time":"2017-01-20T21:59:14+00:00","article_modified_time":"2017-01-21T22:03:24+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/#article","isPartOf":{"@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/"},"author":{"name":"admin","@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/person\/f42878fd07a4b6ba2b7153d4fad5de5e"},"headline":"Mobilit\u00e0: Concluso il confronto sull&#8217;articolato","datePublished":"2017-01-20T21:59:14+00:00","dateModified":"2017-01-21T22:03:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/"},"wordCount":578,"publisher":{"@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#organization"},"articleSection":["ATA","Mobilit\u00e0","Notizie","Personale Docente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/","url":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/","name":"Mobilit\u00e0: Concluso il confronto sull'articolato - Uil Scuola Emilia Romagna","isPartOf":{"@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#website"},"datePublished":"2017-01-20T21:59:14+00:00","dateModified":"2017-01-21T22:03:24+00:00","breadcrumb":{"@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/2017\/01\/20\/mobilita-concluso-il-confronto-sullarticolato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/"},{"@type":"ListItem","position":2,"name":"Mobilit\u00e0: Concluso il confronto sull&#8217;articolato"}]},{"@type":"WebSite","@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#website","url":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/","name":"Uil Scuola Emilia Romagna","description":"La voce libera della scuola","publisher":{"@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#organization","name":"Uil Scuola Emilia Romagna","url":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/logo\/image\/","url":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-content\/uploads\/2017\/04\/cropped-header.png","contentUrl":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-content\/uploads\/2017\/04\/cropped-header.png","width":1000,"height":150,"caption":"Uil Scuola Emilia Romagna"},"image":{"@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/person\/f42878fd07a4b6ba2b7153d4fad5de5e","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aebf815ae2f30ffdae8b8c247273d34c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aebf815ae2f30ffdae8b8c247273d34c?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/author\/admin\/"}]}},"views":1099,"_links":{"self":[{"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/posts\/1183"}],"collection":[{"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/comments?post=1183"}],"version-history":[{"count":2,"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/posts\/1183\/revisions"}],"predecessor-version":[{"id":1187,"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/posts\/1183\/revisions\/1187"}],"wp:attachment":[{"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/media?parent=1183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/categories?post=1183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uilscuolaemiliaromagna.it\/public\/er\/wp-json\/wp\/v2\/tags?post=1183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}